{"id":318,"date":"2007-03-22T20:44:16","date_gmt":"2007-03-22T20:44:16","guid":{"rendered":""},"modified":"2008-01-23T19:24:54","modified_gmt":"2008-01-23T19:24:54","slug":"concurso-de-fotografia-mid","status":"publish","type":"post","link":"https:\/\/blog.federacionfotovasca.org\/eu\/concurso-de-fotografia-mid\/","title":{"rendered":"Concurso de fotografia mi+d"},"content":{"rendered":"<p>La Fundaci\u00f3n para el conocimiento madri+d convoca la tercera edici\u00f3n del  Concurso de Fotograf\u00eda madri+d con el tema de la Ciencia en la ciudad y la  ciudad en la Ciencia. La ciencia est\u00e1 presente en nuestra vida diaria. Muchas  veces oculta y escondida, pasa desapercibida a nuestra mirada. El objetivo de  este concurso es desvelar este mundo, hacer evidente la relaci\u00f3n de la ciencia  con nuestra cotidianidad, mostrar los edificios de la ciencia en su contexto  espacial y presentarlos como parte fundamental en la definici\u00f3n del territorio,  en definitiva, destacar la enorme presencia de la ciencia en nuestras ciudades  poniendo en valor el importante patrimonio arquitect\u00f3nico relacionado con la  ciencia existente en la Comunidad de Madrid.<\/p>\n<p><a href=\"\/joomla\/archivos\/Bases_Concurso_madri+d.pdf\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.federacionfotovasca.org\/joomla\/images\/stories\/Noticias07\/3ConcursoMI+D.jpg\" align=\"left\" height=\"430\" width=\"304\" \/> <\/a><\/p>\n<p>El tema de este a\u00f1o quiere hacer hincapi\u00e9 en la definici\u00f3n y formaci\u00f3n de los  espacios urbanos de la provincia madrile\u00f1a. Si bien las fotograf\u00edas deben  mostrar los edificios relacionados con la ciencia, \u00e9stos no deben ser el objeto  final de la fotograf\u00eda. La organizaci\u00f3n del concurso matiza que no se buscan  dise\u00f1os magn\u00edficos de interiores ni semblantes deslumbrantes de grandes  edificios, sino que las fotograf\u00edas deben servir para mostrar la vinculaci\u00f3n de  la ciencia con nuestra vida diaria. Deben descubrir la ciencia y los espacios de  la ciencia.<\/p>\n<p>En este concurso podr\u00e1n participar todas aquellas personas mayores de edad y  residentes en Espa\u00f1a, sin importar su nacionalidad. Los premios van desde los  1000 \u20ac del Premio del jurado, pasando por los 600 \u20ac del Premio por votaci\u00f3n  popular hasta los 100 \u20ac para las 20 Obras finalistas.<\/p>\n<p>El sistema de participaci\u00f3n se realiza enteramente a trav\u00e9s de internet ya  que los participantes deben cumplimentar un formulario on-line, adjuntando las  fotograf\u00edas desde el sitio web de madri+d. El plazo de recepci\u00f3n de las  fotograf\u00edas ser\u00e1 desde el 9 de marzo hasta las 24:00 horas del 9 de abril de  2007.<\/p>\n<p>De las obras recibidas en plazo a trav\u00e9s de la web de madri+d, el comit\u00e9  organizador seleccionar\u00e1 las obras finalistas que se publicar\u00e1n en dicha web  desde el d\u00eda 12 de abril hasta el 14 de mayo. Tambi\u00e9n se expondr\u00e1n  \u201cvirtualmente\u201d en la VIII Feria Madrid es Ciencia que tendr\u00e1 lugar del 12 al 15  de abril de 2007 en el pabell\u00f3n 10 de los Recintos Feriales Juan Carlos I.<\/p>\n<p>Para m\u00e1s informaci\u00f3n consultar la web: <a href=\"http:\/\/www.madrimasd.org\/cienciaysociedad\/concurso\">http:\/\/www.madrimasd.org\/cienciaysociedad\/concurso<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n para el conocimiento madri+d convoca la tercera edici\u00f3n del Concurso de Fotograf\u00eda madri+d con el tema de la Ciencia en la ciudad y la ciudad en la Ciencia. La ciencia est\u00e1 presente en nuestra vida diaria. Muchas veces &hellip; <a href=\"https:\/\/blog.federacionfotovasca.org\/eu\/concurso-de-fotografia-mid\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[419],"class_list":["post-318","post","type-post","status-publish","format-standard","hentry","category-concursos","tag-concursos"],"_links":{"self":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":0,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}