{"id":4238,"date":"2013-09-10T15:53:26","date_gmt":"2013-09-10T13:53:26","guid":{"rendered":"https:\/\/www.federacionfotovasca.org\/?p=4238"},"modified":"2013-09-10T15:53:26","modified_gmt":"2013-09-10T13:53:26","slug":"candidaturas-premios-nacionales-de-fotografia-cef-2014","status":"publish","type":"post","link":"https:\/\/blog.federacionfotovasca.org\/eu\/candidaturas-premios-nacionales-de-fotografia-cef-2014\/","title":{"rendered":"CANDIDATURAS PREMIOS NACIONALES DE FOTOGRAFIA CEF 2014"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>Estimados amigos;<br \/>\nAdjuntamos a este correo, las candidaturas a los diferentes Premios Nacionales de Fotografia de la C.E.F., enviados\u00a0 por diferentes Federaciones y Entidades.<\/div>\n<p>C\u00f3mo ver\u00e9is, en dos de los apartatados, Mejor Mecenas y Mejor Medio de Difusi\u00f3n, solamente se ha recibido una candidatura por premio, por lo que quedan otorgados de forma autom\u00e1tica.<br \/>\nSolamente se someter\u00e1n a votaci\u00f3n el Premio a Mejor Entidad y a\u00a0 Mejor Fot\u00f3grafo. Esta votaci\u00f3n tendr\u00e1 lugar durante la Asamblea de la CEF, que se celebrar\u00e1 en el pr\u00f3ximo Congreso en La VIla Joiosa, los dias 1 y 2 de Noviembre.<\/p><\/div>\n<p>De igual forma, adjuntamos el listado de Entidades organizadoras de concursos con patrocinio CEF, que tienen derecho a voto, y la hoja de votaci\u00f3n.<br \/>\nAquellas Entidades que no puedan asistir al Congreso, pueden hacer llegar sus votos a trav\u00e9s de su Federaci\u00f3n.<br \/>\nEn el caso de Entidades que no tienen representaci\u00f3n a trav\u00e9s de una federaci\u00f3n, pueden enviar directamente la hoja con sus votos,\u00a0 a la direcci\u00f3n de correo:<\/p><\/div>\n<div><a href=\"mailto:vice-actividades@cefoto.org\" target=\"_blank\">vice-actividades@cefoto.org<\/a>,<br \/>\nEn los archivos comprimidos,\u00a0 encontrar\u00e9is la informaci\u00f3n aportada junto a cada candidatura. \u00a0Muchas gracias a todos.<\/div>\n<\/div>\n<p><b>INFORMACI\u00d3N COMPLEMENTARIA:<\/b><br \/>\n<b>Premio Nacional Mejor Mecenas<\/b>: disponemos de un extenso dossier en formato pdf. que complementa el informe adjunto del Ayuntamiento de \u00c9ibar. Dado que es un archivo de cerca de 70 megas y no hay otra candidatura, no lo adjuntamos en esta comunicaci\u00f3n. Si cualquiera de vosotros quiere revisar esta informaci\u00f3n, rogamos lo comunique respondiendo a este correo. Le indicaremos un link de wetransfer para descargar estos archivos.<br \/>\n<b>Premio Nacional Mejor Medio de Difusi\u00f3n<\/b>: El Col.lectiu Fotogr\u00e0fic F11, nos ha hecho llegar el link al ultimo n\u00famero de su magazine, que no est\u00e1 en el archivo adjunto correspondiente. El enlace es\u00a0<a href=\"http:\/\/issuu.com\/collectiuf22\/docs\/f22_magazine_04\" target=\"_blank\"><span style=\"color: #0000ff; font-family: 'Times New Roman'; font-size: medium;\">http:\/\/issuu.com\/collectiuf22\/<wbr \/>docs\/f22_magazine_04<\/span><\/a><\/div>\n<\/div>\n<p><b>Rogamos pod\u00e1is confirmar la recepci\u00f3n de este correo.<\/b><br \/>\nMuchas gracias de nuevo!<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.1&amp;thid=141048969584049b&amp;mt=application\/pdf&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.1%26disp%3Dsafe%26realattid%3Df_hle68hpj0%26zw&amp;sig=AHIEtbSc1Qxj2wg2kjNfZsoSLN27SA9_CA\" target=\"_blank\"><b>Hoja votacion Premios Nacionales CEF 2014.pdf<\/b><\/a><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.2&amp;thid=141048969584049b&amp;mt=application\/pdf&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.2%26disp%3Dsafe%26realattid%3Df_hle68hqf1%26zw&amp;sig=AHIEtbTY5MNyFaYWqtBsgvtaM7nMLSW1Zw\" target=\"_blank\"><b>PREMIOS NACIONALES CEF 2014 candidaturas presentadas.pdf<\/b><\/a><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.3&amp;thid=141048969584049b&amp;mt=application\/pdf&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.3%26disp%3Dsafe%26realattid%3Df_hle6987q2%26zw&amp;sig=AHIEtbR-7tOaOPfkTW-Quqwvo1g_5fEaOw\" target=\"_blank\"><b>CANDIDATURA MEJOR MECENAS.pdf<\/b><\/a><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.4&amp;thid=141048969584049b&amp;mt=application\/vnd.ms-excel&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.4%26disp%3Dsafe%26realattid%3Df_hle69un33%26zw&amp;sig=AHIEtbRqCpN79Dnh4ShyEwP00Yv7nGY5Mw\" target=\"_blank\">Entidades con derecho a voto.pdf<\/a><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.5&amp;thid=141048969584049b&amp;mt=application\/zip&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.5%26disp%3Dsafe%26realattid%3Df_hle6b8ru4%26zw&amp;sig=AHIEtbTPT0pZpnxUjHDbv7_hX79ypzOM4g\" target=\"_blank\"><b>CANDIDATURAS MEJOR ENTIDAD<\/b><\/a><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.6&amp;thid=141048969584049b&amp;mt=application\/zip&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.6%26disp%3Dsafe%26realattid%3Df_hle6bvxp5%26zw&amp;sig=AHIEtbQKCZa-MoafzBQevxX6_nUdS3LeNw\" target=\"_blank\"><b>CANDIDATURAS MEJOR ARTISTA<\/b><\/a><\/div>\n<div><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=gmail&amp;attid=0.7&amp;thid=141048969584049b&amp;mt=application\/pdf&amp;url=https:\/\/mail.google.com\/mail\/u\/0\/?ui%3D2%26ik%3D514898afdd%26view%3Datt%26th%3D141048969584049b%26attid%3D0.7%26disp%3Dsafe%26realattid%3Df_hle6cvx36%26zw&amp;sig=AHIEtbRQxIlZSmPoJlIU43FcWZPjpc1emg\" target=\"_blank\"><b>CANDIDATURA MEJOR MEDIO DIFUSION Proyecto f22 magazine<\/b><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estimados amigos; Adjuntamos a este correo, las candidaturas a los diferentes Premios Nacionales de Fotografia de la C.E.F., enviados\u00a0 por diferentes Federaciones y Entidades. C\u00f3mo ver\u00e9is, en dos de los apartatados, Mejor Mecenas y Mejor Medio de Difusi\u00f3n, solamente se &hellip; <a href=\"https:\/\/blog.federacionfotovasca.org\/eu\/candidaturas-premios-nacionales-de-fotografia-cef-2014\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4238","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/4238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/comments?post=4238"}],"version-history":[{"count":1,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/4238\/revisions"}],"predecessor-version":[{"id":4239,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/4238\/revisions\/4239"}],"wp:attachment":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/media?parent=4238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/categories?post=4238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/tags?post=4238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}