{"id":453,"date":"2007-08-16T09:53:02","date_gmt":"2007-08-16T09:53:02","guid":{"rendered":""},"modified":"2008-01-10T20:37:45","modified_gmt":"2008-01-10T20:37:45","slug":"profesionales-de-fotografia-solicitan-el-desarrollo-de-la-normativa-sobre-derechos-de-autor","status":"publish","type":"post","link":"https:\/\/blog.federacionfotovasca.org\/eu\/profesionales-de-fotografia-solicitan-el-desarrollo-de-la-normativa-sobre-derechos-de-autor\/","title":{"rendered":"Profesionales de fotograf\u00eda solicitan el desarrollo de la normativa sobre derechos de autor"},"content":{"rendered":"<p align=\"justify\">Los profesionales de la fotograf\u00eda solicitan en Valencia el desarrollo de la normativa sobre derechos de autor<\/p>\n<p align=\"justify\">La presidenta de la Federaci\u00f3n Espa\u00f1ola de Profesionales de la Fotograf\u00eda y de la Imagen (FEPFI), Bel\u00e9n Caballero, reclam\u00f3 hoy el desarrollo de la legislaci\u00f3n sobre derechos de autor en el sector de la fotograf\u00eda ante &#8216;los nuevos casos que se puedan dar&#8217; con la introducci\u00f3n de las nuevas tecnolog\u00edas ya que, a su juicio, este \u00e1rea vive momentos de &#8216;desconocimiento y de carencias&#8217;.<\/p>\n<p align=\"justify\">Caballero realiz\u00f3 estas declaraciones con motivo de la rueda de prensa celebrada junto al presidente de la Federaci\u00f3n Europea de Fot\u00f3grafos, Luc Peeter, y el presidente de la Asociaci\u00f3n Valenciana de Fot\u00f3grafos, Ricardo Carrillo, para presentar el I Congreso Europeo de Fot\u00f3grafos Profesionales que se celebrar\u00e1 entre el 11 y el 13 de febrero en la ciudad de Valencia, y en el que se abordar\u00e1 en una de las ponencias programadas los derechos de autor sobre la fotograf\u00eda y la imagen.<\/p>\n<p align=\"justify\">En este sentido, la presidenta de la agrupaci\u00f3n nacional se\u00f1al\u00f3 que ante esta normativa existe &#8216;una situaci\u00f3n de desconocimiento&#8217; y explic\u00f3 que hay que &#8216;desarrollar la legislaci\u00f3n que existe y todo lo necesario para los nuevos casos que se puedan dar&#8217;.<\/p>\n<p align=\"justify\">De este modo expuso que las nuevas tecnolog\u00edas &#8216;producen situaciones que antes eran impensables&#8217;. Ante esto, asegur\u00f3 que la federaci\u00f3n tiene &#8216;una importante labor de concienciaci\u00f3n y educaci\u00f3n para evitar posibles disputas por desconocimiento&#8217;.<\/p>\n<p align=\"justify\">En cuanto, al I Congreso Europeo de Fot\u00f3grafos Profesionales, que espera reunir a 1.500 asistentes de toda Europa, indic\u00f3 que &#8216;no se dud\u00f3 en ning\u00fan momento&#8217; de que se celebrase en Valencia ya que en ella trabaja, seg\u00fan asegur\u00f3, la asociaci\u00f3n &#8216;con mayor n\u00famero de asociados &#8211;alrededor de 390&#8211;, la de mayor prestigio y mayor capacidad organizativa&#8217;.<\/p>\n<p align=\"justify\">La agrupaci\u00f3n valenciana celebra desde hace 25 a\u00f1os un congreso nacional cada dos a\u00f1os del que, seg\u00fan Luc Peeter, &#8216;naci\u00f3 la idea de abrirlo a toda Europa&#8217; y que estaba caracterizado &#8216;por su mezcla fabulosa de ponentes&#8217;.<\/p>\n<p align=\"justify\">El representante de la federaci\u00f3n europea asegur\u00f3 que el programa de esta primera edici\u00f3n del congreso ser\u00e1 &#8216;muy interesante&#8217; con tem\u00e1ticas que abarcan desde el retrato, las bodas, la fotograf\u00eda arquitect\u00f3nica, la publicitaria o los reportajes.<\/p>\n<p align=\"justify\">Adem\u00e1s, contar\u00e1 con la presencia de 12 ponentes llegados de Irlanda, Gran Breta\u00f1a, Holanda, Francia, Alemania, Austria, B\u00e9lgica, Italia, Rep\u00fablica Checa, Espa\u00f1a, Portugal y Finlandia. Lo que motiva la inclusi\u00f3n de traductores de diez idiomas, a parte del espa\u00f1ol y el ingl\u00e9s que ser\u00e1n los oficiales.<\/p>\n<p align=\"justify\">Peeter asegur\u00f3 que el congreso busca crear &#8216;una comuni\u00f3n&#8217; entre los profesionales europeos de la fotograf\u00eda y la imagen lo que, seg\u00fan explic\u00f3, &#8216;se consigue al concentrarse en las cosas que tenemos en com\u00fan&#8217;. Por este motivo, indic\u00f3 que el congreso se realizar\u00e1 bajo el lema &#8216;Id\u00e9nticos en la diversidad&#8217;.<\/p>\n<p align=\"justify\">La reuni\u00f3n estar\u00e1 abierta a los fot\u00f3grafos &#8216;no profesionales&#8217;, y contar\u00e1 con un programa paralelo encabezado por una feria de productos fotogr\u00e1ficos, con 45 firmas comerciales presentes, y una exposici\u00f3n de los trabajos presentados a los concursos que se celebrar\u00e1n a la vez que el certamen.<\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los profesionales de la fotograf\u00eda solicitan en Valencia el desarrollo de la normativa sobre derechos de autor La presidenta de la Federaci\u00f3n Espa\u00f1ola de Profesionales de la Fotograf\u00eda y de la Imagen (FEPFI), Bel\u00e9n Caballero, reclam\u00f3 hoy el desarrollo de &hellip; <a href=\"https:\/\/blog.federacionfotovasca.org\/eu\/profesionales-de-fotografia-solicitan-el-desarrollo-de-la-normativa-sobre-derechos-de-autor\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,15],"tags":[418],"class_list":["post-453","post","type-post","status-publish","format-standard","hentry","category-fotografos","category-general","tag-noticias"],"_links":{"self":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":0,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/453\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/media?parent=453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/categories?post=453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/tags?post=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}