{"id":628,"date":"2008-01-30T19:48:18","date_gmt":"2008-01-30T19:48:18","guid":{"rendered":"https:\/\/www.federacionfotovasca.org\/?p=628"},"modified":"2008-01-30T19:48:18","modified_gmt":"2008-01-30T19:48:18","slug":"certamenes-fotograficos-de-la-cfe","status":"publish","type":"post","link":"https:\/\/blog.federacionfotovasca.org\/eu\/certamenes-fotograficos-de-la-cfe\/","title":{"rendered":"Certamenes fotograficos de la CFE"},"content":{"rendered":"<p>La Confederacion Espa\u00f1ola de Fotograf\u00eda ha convocado dos nuevos Cert\u00e1menes nacionales:<\/p>\n<ul>\n<li>El primero de ellos ser\u00e1 clasificatorio para representar a Espa\u00f1a en la 14\u00aa Bienal de Naturaleza y el tema obligatorio ser\u00e1 PAISAJES DE ESPA\u00d1A. <a href=\"\/archivos\/VII_CERTAMEN_FOTOGRAFICO_DE_LA_CEF.pdf\" target=\"_blank\">Ver Bases completas<\/a>.<\/li>\n<li>El segundo ser\u00e1 clasificatorio para representar a Espa\u00f1a en la 30\u00aa Bienal de la Juventud de la FIAP para fotografos menos de 21 a\u00f1os. <a href=\"\/archivos\/VIII_CERTAMEN_FOTOGRAFICO_DE_LA_CEF.pdf\" target=\"_blank\">Ver Bases completas<\/a>.<\/li>\n<\/ul>\n<p>Os rogamos la m\u00e1xima difusi\u00f3n de estos cert\u00e1menes entre vuestros asociados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Confederacion Espa\u00f1ola de Fotograf\u00eda ha convocado dos nuevos Cert\u00e1menes nacionales: El primero de ellos ser\u00e1 clasificatorio para representar a Espa\u00f1a en la 14\u00aa Bienal de Naturaleza y el tema obligatorio ser\u00e1 PAISAJES DE ESPA\u00d1A. Ver Bases completas. El segundo &hellip; <a href=\"https:\/\/blog.federacionfotovasca.org\/eu\/certamenes-fotograficos-de-la-cfe\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,9],"tags":[10,419,416],"class_list":["post-628","post","type-post","status-publish","format-standard","hentry","category-concursos","category-federacion","tag-cef","tag-concursos","tag-federacion"],"_links":{"self":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":0,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/posts\/628\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/media?parent=628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/categories?post=628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.federacionfotovasca.org\/eu\/wp-json\/wp\/v2\/tags?post=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}